{"id":426,"date":"2020-11-28T19:56:37","date_gmt":"2020-11-28T19:56:37","guid":{"rendered":"http:\/\/sophie-cohen-psychologue.com\/?p=426"},"modified":"2021-04-04T18:46:01","modified_gmt":"2021-04-04T18:46:01","slug":"sueurs-froides","status":"publish","type":"post","link":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/","title":{"rendered":"Hitchcock et la psychanalyse | <i>Sueurs froides<\/i>"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"770\" height=\"578\" src=\"http:\/\/sophie-cohen-psychologue.com\/wp-content\/uploads\/2020\/11\/Blog-Sueurs-froides.png\" alt=\"Blog | Sophie Cohen psychologue Paris 5e\" class=\"wp-image-430\" srcset=\"https:\/\/sophie-cohen-psychologue.com\/wp-content\/uploads\/2020\/11\/Blog-Sueurs-froides.png 770w, https:\/\/sophie-cohen-psychologue.com\/wp-content\/uploads\/2020\/11\/Blog-Sueurs-froides-300x225.png 300w, https:\/\/sophie-cohen-psychologue.com\/wp-content\/uploads\/2020\/11\/Blog-Sueurs-froides-768x576.png 768w\" sizes=\"auto, (max-width: 770px) 100vw, 770px\" \/><\/figure>\n\n\n\n<p>James Stewart a le <em>vertige<\/em>. Ou plut\u00f4t, il est <em>acrophobe&nbsp;<\/em>: il souffre d\u2019une <em>peur <\/em>panique du vide et des hauteurs. Il \u00e9tait policier mais, rong\u00e9 par la <em>culpabilit\u00e9<\/em> apr\u00e8s la <em>mort<\/em> d\u2019un coll\u00e8gue tomb\u00e9 d\u2019un toit alors qu\u2019il essayait de le sauver, il a d\u00e9missionn\u00e9. \u00ab&nbsp;<i>Seul un choc \u00e9motionnel pourrait me gu\u00e9rir<\/i>&nbsp;\u00bb, dit-il. Une de ses connaissances lui fait part de son <em>inqui\u00e9tude<\/em> concernant sa femme, Kim Novak, au comportement \u00e9trange. Elle serait hant\u00e9e par l\u2019esprit d\u2019une anc\u00eatre. Le mari craint qu\u2019elle ne mette fin \u00e0 ses jours et demande \u00e0 James Stewart de la suivre pour \u00e9viter le pire. Ce dernier accepte la mission, mais il a <em>peur du vide<\/em>\u2026 Il verra l\u2019h\u00e9ro\u00efne se jeter du haut d\u2019un clocher, t\u00e9tanis\u00e9, impuissant \u00e0 \u00e9viter ce qu\u2019il croit \u00eatre un <em>suicide<\/em>. Plus tard, il rencontrera une autre femme, toujours Kim Novak, qui lui rappellera \u00e9trangement la belle au clocher.<\/p>\n\n\n\n<p>La <em>peur du vide<\/em> est ici une peur de se jeter dans le vide, une peur de perdre le contr\u00f4le, de chuter.<\/p>\n\n\n\n<p><em>L\u2019angoisse<\/em> du h\u00e9ros, par un effet miroir, trouve sa mise en acte chez l\u2019h\u00e9ro\u00efne&nbsp;: Kim Novak chute dans la baie de San Francisco avant de chuter du haut du clocher.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u2019o\u00f9 viennent les phobies&nbsp;?<\/h2>\n\n\n\n<p>Les <em>phobies<\/em>, <em>peurs <\/em>excessives, irraisonn\u00e9es, peuvent s\u2019attacher \u00e0 tout ou presque&nbsp;: <em>phobies d\u2019animaux<\/em>, de ph\u00e9nom\u00e8nes naturels, de la profondeur, du noir, de l\u2019eau, des transports, des tunnels, des ponts, des ascenseurs, du sang&nbsp;; <em>phobies<\/em> li\u00e9es \u00e0 des situations collectives ou interpersonnelles\u2026<\/p>\n\n\n\n<p>Le <i>DSM-5<\/i> \u2013 manuel am\u00e9ricain des troubles mentaux \u2013 classe les <em>phobies<\/em> en quatre cat\u00e9gories&nbsp;: trouble panique avec agoraphobie, agoraphobie sans trouble panique, phobie sp\u00e9cifique, phobie sociale. Classement n\u00e9cessaire mais pas suffisant&nbsp;: la diversit\u00e9 des causalit\u00e9s des phobies n\u2019est pas mentionn\u00e9e, ni interrog\u00e9e la fa\u00e7on dont elles s\u2019articulent avec l\u2019histoire singuli\u00e8re d\u2019un individu.<\/p>\n\n\n\n<p>Pour <em>Freud<\/em>, la <em>phobie<\/em> est une forme d\u2019<em>angoisse<\/em> qui s\u2019est fix\u00e9e sur un objet&nbsp;\u2013 dans le film, la <em>peur panique du vide<\/em>. Cet objet externe devient alors d\u00e9positaire de l\u2019angoisse interne. En \u00e9vitant l\u2019objet, on r\u00e9duit l\u2019angoisse. La phobie peut devenir le pivot autour duquel l\u2019individu organisera toute son existence, contraint de mettre en place de complexes strat\u00e9gies d\u2019\u00e9vitement.<\/p>\n\n\n\n<p>L\u2019objet de la <em>phobie<\/em> n\u2019a pas un sens propre. Il est investi d\u2019un sens particulier pour l\u2019individu concern\u00e9, il est ins\u00e9r\u00e9 dans une histoire dont les fils doivent \u00eatre d\u00e9m\u00eal\u00e9s. C\u2019est \u00e0 un travail de d\u00e9liaison d\u2019anciennes et co\u00fbteuses strat\u00e9gies psychiques qu\u2019il faut s\u2019attacher.<\/p>\n\n\n\n<p>En mettant l\u2019accent sur les circonstances de l\u2019apparition de la<em> phobie,<\/em> sur ce qui l\u2019a rendue n\u00e9cessaire, on \u00e9vite de la voir r\u00e9appara\u00eetre sous une autre forme. C\u2019est le risque lorsque l\u2019on se contente de l\u2019\u00e9radiquer.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.youtube.com\/watch?v=Z5jvQwwHQNY\" target=\"_blank\" rel=\"noreferrer noopener\">Voir la bande-annonce<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>James Stewart a le vertige. Ou plut\u00f4t, il est acrophobe&nbsp;: il souffre d\u2019une peur panique du vide et des hauteurs. Il \u00e9tait policier mais, rong\u00e9 par la culpabilit\u00e9 apr\u00e8s la mort d\u2019un coll\u00e8gue tomb\u00e9 d\u2019un toit alors qu\u2019il essayait de le sauver, il a d\u00e9missionn\u00e9. \u00ab&nbsp;Seul un choc \u00e9motionnel pourrait me gu\u00e9rir&nbsp;\u00bb, dit-il. Une de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-426","post","type-post","status-publish","format-standard","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hitchcock et la psychanalyse : \u00ab Sueurs froides \u00bb | Sophie Cohen, psychologue Paris 5e<\/title>\n<meta name=\"description\" content=\"James Stewart a le vertige. Ou plut\u00f4t, il est acrophobe : il souffre d\u2019une peur panique du vide et des hauteurs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hitchcock et la psychanalyse : \u00ab Sueurs froides \u00bb | Sophie Cohen, psychologue Paris 5e\" \/>\n<meta property=\"og:description\" content=\"James Stewart a le vertige. Ou plut\u00f4t, il est acrophobe : il souffre d\u2019une peur panique du vide et des hauteurs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/\" \/>\n<meta property=\"og:site_name\" content=\"Sophie Cohen, psychologue Paris 5e\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-28T19:56:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-04T18:46:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/sophie-cohen-psychologue.com\/wp-content\/uploads\/2020\/11\/Blog-Sueurs-froides.png\" \/>\n<meta name=\"author\" content=\"Sophie Cohen, psychologue Paris 5e\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sophie Cohen, psychologue Paris 5e\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/index.php\\\/2020\\\/11\\\/28\\\/sueurs-froides\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/index.php\\\/2020\\\/11\\\/28\\\/sueurs-froides\\\/\"},\"author\":{\"name\":\"Sophie Cohen, psychologue Paris 5e\",\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/#\\\/schema\\\/person\\\/fca3c7ff1eb34da06cd173b137d4852a\"},\"headline\":\"Hitchcock et la psychanalyse | Sueurs froides\",\"datePublished\":\"2020-11-28T19:56:37+00:00\",\"dateModified\":\"2021-04-04T18:46:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/index.php\\\/2020\\\/11\\\/28\\\/sueurs-froides\\\/\"},\"wordCount\":531,\"publisher\":{\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/#\\\/schema\\\/person\\\/fca3c7ff1eb34da06cd173b137d4852a\"},\"image\":{\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/index.php\\\/2020\\\/11\\\/28\\\/sueurs-froides\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/sophie-cohen-psychologue.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Blog-Sueurs-froides.png\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/index.php\\\/2020\\\/11\\\/28\\\/sueurs-froides\\\/\",\"url\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/index.php\\\/2020\\\/11\\\/28\\\/sueurs-froides\\\/\",\"name\":\"Hitchcock et la psychanalyse : \u00ab Sueurs froides \u00bb | Sophie Cohen, psychologue Paris 5e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/index.php\\\/2020\\\/11\\\/28\\\/sueurs-froides\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/index.php\\\/2020\\\/11\\\/28\\\/sueurs-froides\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/sophie-cohen-psychologue.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Blog-Sueurs-froides.png\",\"datePublished\":\"2020-11-28T19:56:37+00:00\",\"dateModified\":\"2021-04-04T18:46:01+00:00\",\"description\":\"James Stewart a le vertige. Ou plut\u00f4t, il est acrophobe : il souffre d\u2019une peur panique du vide et des hauteurs.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/index.php\\\/2020\\\/11\\\/28\\\/sueurs-froides\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/index.php\\\/2020\\\/11\\\/28\\\/sueurs-froides\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/index.php\\\/2020\\\/11\\\/28\\\/sueurs-froides\\\/#primaryimage\",\"url\":\"http:\\\/\\\/sophie-cohen-psychologue.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Blog-Sueurs-froides.png\",\"contentUrl\":\"http:\\\/\\\/sophie-cohen-psychologue.com\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Blog-Sueurs-froides.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/index.php\\\/2020\\\/11\\\/28\\\/sueurs-froides\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hitchcock et la psychanalyse | Sueurs froides\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/#website\",\"url\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/\",\"name\":\"Sophie Cohen, psychologue Paris 5e\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/#\\\/schema\\\/person\\\/fca3c7ff1eb34da06cd173b137d4852a\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/sophie-cohen-psychologue.com\\\/#\\\/schema\\\/person\\\/fca3c7ff1eb34da06cd173b137d4852a\",\"name\":\"Sophie Cohen, psychologue Paris 5e\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d55f155746c19096fe7e8a9d093fa497cd007adb27fb0bcf3b61cd31a928956a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d55f155746c19096fe7e8a9d093fa497cd007adb27fb0bcf3b61cd31a928956a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d55f155746c19096fe7e8a9d093fa497cd007adb27fb0bcf3b61cd31a928956a?s=96&d=mm&r=g\",\"caption\":\"Sophie Cohen, psychologue Paris 5e\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d55f155746c19096fe7e8a9d093fa497cd007adb27fb0bcf3b61cd31a928956a?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/sophie-cohen-psychologue.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hitchcock et la psychanalyse : \u00ab Sueurs froides \u00bb | Sophie Cohen, psychologue Paris 5e","description":"James Stewart a le vertige. Ou plut\u00f4t, il est acrophobe : il souffre d\u2019une peur panique du vide et des hauteurs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/","og_locale":"fr_FR","og_type":"article","og_title":"Hitchcock et la psychanalyse : \u00ab Sueurs froides \u00bb | Sophie Cohen, psychologue Paris 5e","og_description":"James Stewart a le vertige. Ou plut\u00f4t, il est acrophobe : il souffre d\u2019une peur panique du vide et des hauteurs.","og_url":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/","og_site_name":"Sophie Cohen, psychologue Paris 5e","article_published_time":"2020-11-28T19:56:37+00:00","article_modified_time":"2021-04-04T18:46:01+00:00","og_image":[{"url":"http:\/\/sophie-cohen-psychologue.com\/wp-content\/uploads\/2020\/11\/Blog-Sueurs-froides.png","type":"","width":"","height":""}],"author":"Sophie Cohen, psychologue Paris 5e","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Sophie Cohen, psychologue Paris 5e","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/#article","isPartOf":{"@id":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/"},"author":{"name":"Sophie Cohen, psychologue Paris 5e","@id":"https:\/\/sophie-cohen-psychologue.com\/#\/schema\/person\/fca3c7ff1eb34da06cd173b137d4852a"},"headline":"Hitchcock et la psychanalyse | Sueurs froides","datePublished":"2020-11-28T19:56:37+00:00","dateModified":"2021-04-04T18:46:01+00:00","mainEntityOfPage":{"@id":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/"},"wordCount":531,"publisher":{"@id":"https:\/\/sophie-cohen-psychologue.com\/#\/schema\/person\/fca3c7ff1eb34da06cd173b137d4852a"},"image":{"@id":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/#primaryimage"},"thumbnailUrl":"http:\/\/sophie-cohen-psychologue.com\/wp-content\/uploads\/2020\/11\/Blog-Sueurs-froides.png","articleSection":["Blog"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/","url":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/","name":"Hitchcock et la psychanalyse : \u00ab Sueurs froides \u00bb | Sophie Cohen, psychologue Paris 5e","isPartOf":{"@id":"https:\/\/sophie-cohen-psychologue.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/#primaryimage"},"image":{"@id":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/#primaryimage"},"thumbnailUrl":"http:\/\/sophie-cohen-psychologue.com\/wp-content\/uploads\/2020\/11\/Blog-Sueurs-froides.png","datePublished":"2020-11-28T19:56:37+00:00","dateModified":"2021-04-04T18:46:01+00:00","description":"James Stewart a le vertige. Ou plut\u00f4t, il est acrophobe : il souffre d\u2019une peur panique du vide et des hauteurs.","breadcrumb":{"@id":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/#primaryimage","url":"http:\/\/sophie-cohen-psychologue.com\/wp-content\/uploads\/2020\/11\/Blog-Sueurs-froides.png","contentUrl":"http:\/\/sophie-cohen-psychologue.com\/wp-content\/uploads\/2020\/11\/Blog-Sueurs-froides.png"},{"@type":"BreadcrumbList","@id":"https:\/\/sophie-cohen-psychologue.com\/index.php\/2020\/11\/28\/sueurs-froides\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/sophie-cohen-psychologue.com\/"},{"@type":"ListItem","position":2,"name":"Hitchcock et la psychanalyse | Sueurs froides"}]},{"@type":"WebSite","@id":"https:\/\/sophie-cohen-psychologue.com\/#website","url":"https:\/\/sophie-cohen-psychologue.com\/","name":"Sophie Cohen, psychologue Paris 5e","description":"","publisher":{"@id":"https:\/\/sophie-cohen-psychologue.com\/#\/schema\/person\/fca3c7ff1eb34da06cd173b137d4852a"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sophie-cohen-psychologue.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/sophie-cohen-psychologue.com\/#\/schema\/person\/fca3c7ff1eb34da06cd173b137d4852a","name":"Sophie Cohen, psychologue Paris 5e","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/d55f155746c19096fe7e8a9d093fa497cd007adb27fb0bcf3b61cd31a928956a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d55f155746c19096fe7e8a9d093fa497cd007adb27fb0bcf3b61cd31a928956a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d55f155746c19096fe7e8a9d093fa497cd007adb27fb0bcf3b61cd31a928956a?s=96&d=mm&r=g","caption":"Sophie Cohen, psychologue Paris 5e"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/d55f155746c19096fe7e8a9d093fa497cd007adb27fb0bcf3b61cd31a928956a?s=96&d=mm&r=g"},"sameAs":["http:\/\/sophie-cohen-psychologue.com"]}]}},"_links":{"self":[{"href":"https:\/\/sophie-cohen-psychologue.com\/index.php\/wp-json\/wp\/v2\/posts\/426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sophie-cohen-psychologue.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sophie-cohen-psychologue.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sophie-cohen-psychologue.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sophie-cohen-psychologue.com\/index.php\/wp-json\/wp\/v2\/comments?post=426"}],"version-history":[{"count":7,"href":"https:\/\/sophie-cohen-psychologue.com\/index.php\/wp-json\/wp\/v2\/posts\/426\/revisions"}],"predecessor-version":[{"id":454,"href":"https:\/\/sophie-cohen-psychologue.com\/index.php\/wp-json\/wp\/v2\/posts\/426\/revisions\/454"}],"wp:attachment":[{"href":"https:\/\/sophie-cohen-psychologue.com\/index.php\/wp-json\/wp\/v2\/media?parent=426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sophie-cohen-psychologue.com\/index.php\/wp-json\/wp\/v2\/categories?post=426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sophie-cohen-psychologue.com\/index.php\/wp-json\/wp\/v2\/tags?post=426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}